{"id":5257,"date":"2024-11-29T20:54:07","date_gmt":"2024-11-29T20:54:07","guid":{"rendered":"https:\/\/sr2rec.com\/karriere\/"},"modified":"2026-02-03T16:49:23","modified_gmt":"2026-02-03T16:49:23","slug":"karriere","status":"publish","type":"page","link":"https:\/\/sr2rec.com\/de\/karriere\/","title":{"rendered":"Karriere"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; full_height=&#8220;yes&#8220; video_bg=&#8220;use_video&#8220; video_mp4=&#8220;https:\/\/sr2rec.com\/wp-content\/uploads\/2025\/03\/Website-homepage_V5_27_08_2024-1.mp4&#8243; background_video_loading=&#8220;default&#8220; scene_position=&#8220;center&#8220; constrain_group_1=&#8220;yes&#8220; constrain_group_3=&#8220;yes&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#000000&#8243; color_overlay_2=&#8220;#000000&#8243; advanced_gradient_angle=&#8220;180&#8243; overlay_strength=&#8220;0.5&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; parallax_bg=&#8220;true&#8220; parallax_bg_speed=&#8220;medium&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;center&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h1>KARRIERE<\/h1>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#191919&#8243; bg_image=&#8220;89&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;center center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; bottom_padding=&#8220;2%&#8220; top_padding_tablet=&#8220;10%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;animated-bg&#8220; id=&#8220;Career-paths&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#191919&#8243; color_overlay_2=&#8220;#191919&#8243; overlay_strength=&#8220;1&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;center&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"text-align: center;\">WERDEN SIE TEIL <span style=\"color: #13bed7;\">UNSERER REISE<\/span><\/h2>\n<p style=\"text-align: center;\">Wer hier ist, sucht nicht einfach nur einen Job \u2013 sondern bringt Ehrgeiz, Motivation und den Wunsch mit, eine Karriere zu starten, die fordert, f\u00f6rdert und dabei hilft, das volle Potenzial zu entfalten. Gesucht werden engagierte Pers\u00f6nlichkeiten, die in einem Umfeld aufbl\u00fchen, in dem es keine Grenzen gibt. Zwei klar definierte Karrieremodelle sorgen daf\u00fcr, dass Weiterentwicklung nicht dem Zufall \u00fcberlassen wird \u2013 gemeinsam mit einem Team, das Impact lebt.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;center&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;30&#8243; custom_height_tablet=&#8220;5&#8243;][nectar_cta btn_style=&#8220;text-reveal&#8220; heading_tag=&#8220;h4&#8243; border_radius=&#8220;10&#8243; link_type=&#8220;regular&#8220; button_color=&#8220;default&#8220; button_color_hover=&#8220;#13bed7&#8243; text_color=&#8220;#ffffff&#8220; text_color_hover=&#8220;#ffffff&#8220; button_border_color=&#8220;#ffffff&#8220; button_border_color_hover=&#8220;#13bed7&#8243; button_border_thickness=&#8220;1px&#8220; alignment=&#8220;center&#8220; alignment_tablet=&#8220;default&#8220; alignment_phone=&#8220;default&#8220; constrain_group_1=&#8220;yes&#8220; constrain_group_2=&#8220;yes&#8220; constrain_group_3=&#8220;yes&#8220; constrain_group_4=&#8220;yes&#8220; display=&#8220;inline&#8220; display_tablet=&#8220;inline-block&#8220; display_phone=&#8220;inline-block&#8220; icon_family=&#8220;none&#8220; link_text=&#8220;SALES-ROUTE&#8220; url=&#8220;#&#8220; padding_top=&#8220;10px&#8220; padding_bottom=&#8220;10px&#8220; padding_left=&#8220;20px&#8220; padding_right=&#8220;20px&#8220; class=&#8220;career-path-selector&#8220; margin_left=&#8220;10px&#8220; margin_right=&#8220;10px&#8220; margin_top=&#8220;10px&#8220; margin_bottom=&#8220;10px&#8220;][nectar_cta btn_style=&#8220;text-reveal&#8220; heading_tag=&#8220;h4&#8243; border_radius=&#8220;10&#8243; link_type=&#8220;regular&#8220; button_color=&#8220;default&#8220; button_color_hover=&#8220;#13bed7&#8243; text_color=&#8220;#ffffff&#8220; text_color_hover=&#8220;#ffffff&#8220; button_border_color=&#8220;#ffffff&#8220; button_border_color_hover=&#8220;#13bed7&#8243; button_border_thickness=&#8220;1px&#8220; alignment=&#8220;center&#8220; alignment_tablet=&#8220;default&#8220; alignment_phone=&#8220;default&#8220; constrain_group_1=&#8220;yes&#8220; constrain_group_2=&#8220;yes&#8220; constrain_group_3=&#8220;yes&#8220; constrain_group_4=&#8220;yes&#8220; display=&#8220;inline&#8220; display_tablet=&#8220;inline-block&#8220; display_phone=&#8220;inline-block&#8220; icon_family=&#8220;none&#8220; link_text=&#8220;LEADERSHIP-ROUTE&#8220; url=&#8220;#&#8220; padding_top=&#8220;10px&#8220; padding_bottom=&#8220;10px&#8220; padding_left=&#8220;20px&#8220; padding_right=&#8220;20px&#8220; class=&#8220;career-path-selector&#8220; margin_left=&#8220;10px&#8220; margin_right=&#8220;10px&#8220; margin_top=&#8220;10px&#8220; margin_bottom=&#8220;10px&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;30&#8243; custom_height_tablet=&#8220;5&#8243;][vc_column_text css=&#8220;&#8220; el_class=&#8220;career-path-description&#8220; text_direction=&#8220;default&#8220;]Bef\u00f6rderungspl\u00e4ne starten, sobald \u00fcber einen Zeitraum von drei Monaten konstant auf dem erforderlichen Level gearbeitet wird \u2013 danach beginnt ein strukturierter 6-monatiger Bef\u00f6rderungsprozess.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][carousel script=&#8220;flickity&#8220; flickity_formatting=&#8220;default&#8220; desktop_cols_flickity=&#8220;3&#8243; desktop_small_cols_flickity=&#8220;3&#8243; tablet_cols_flickity=&#8220;2&#8243; phone_cols_flickity=&#8220;1&#8243; flickity_controls=&#8220;next_prev_arrows_overlaid&#8220; color=&#8220;default&#8220; flickity_overflow=&#8220;visible&#8220; flickity_wrap_around=&#8220;no-wrap&#8220; flickity_spacing=&#8220;30px&#8220; flickity_column_vertical_alignment=&#8220;default&#8220; column_padding=&#8220;0&#8243; flickity_element_spacing=&#8220;default&#8220; border_radius=&#8220;none&#8220;][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343345-0&#8243; tab_id=&#8220;1770137343345-2&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4769&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">TRAINEE CONSULTANT<\/span><\/h3>\n[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343406-9&#8243; tab_id=&#8220;1770137343407-9&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4773&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">CONSULTANT<\/span><\/h3>\n<p>60.000\u202f\u00a3 Umsatz in 6 Monaten[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343451-9&#8243; tab_id=&#8220;1770137343452-5&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4763&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">SENIOR CONSULTANT<\/span><\/h3>\n<p>150.000\u202f\u00a3 Umsatz in 12 Monaten[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343484-8&#8243; tab_id=&#8220;1770137343484-6&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4779&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">PRINCIPAL CONSULTANT<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">250.000\u202f\u00a3 Umsatz in 12 Monaten<\/span>[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343534-7&#8243; tab_id=&#8220;1770137343534-0&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4776&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">LEAD PRINCIPAL<\/span><\/h3>\n<p>350.000\u202f\u00a3 Umsatz im Contracting-Bereich oder<br \/>\n300.000\u202f\u00a3 im Festanstellungsbereich innerhalb von 12 Monaten[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343567-6&#8243; tab_id=&#8220;1770137343568-3&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4782&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">MANAGING CONSULTANT<\/span><\/h3>\n<p>450.000\u202f\u00a3 Umsatz im Contracting-Bereich oder<br \/>\n400.000\u202f\u00a3 im Festanstellungsbereich innerhalb von 12 Monaten[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343618-9&#8243; tab_id=&#8220;1770137343619-5&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4841&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">ASSOCIATE DIRECTOR<\/span><\/h3>\n<p>550.000\u202f\u00a3 Umsatz im Contracting-Bereich oder<br \/>\n500.000\u202f\u00a3 im Festanstellungsbereich innerhalb von 12 Monaten[\/vc_column_text][\/item][\/carousel][carousel script=&#8220;flickity&#8220; flickity_formatting=&#8220;default&#8220; desktop_cols_flickity=&#8220;3&#8243; desktop_small_cols_flickity=&#8220;3&#8243; tablet_cols_flickity=&#8220;2&#8243; phone_cols_flickity=&#8220;1&#8243; flickity_controls=&#8220;next_prev_arrows_overlaid&#8220; color=&#8220;default&#8220; flickity_overflow=&#8220;visible&#8220; flickity_wrap_around=&#8220;no-wrap&#8220; flickity_spacing=&#8220;30px&#8220; flickity_column_vertical_alignment=&#8220;default&#8220; column_padding=&#8220;0&#8243; flickity_element_spacing=&#8220;default&#8220; border_radius=&#8220;none&#8220;][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343667-5&#8243; tab_id=&#8220;1770137343667-4&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4763&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">SENIOR CONSULTANT<\/span><\/h3>\n<p>Mentoren-\/Buddy-Schema-Schulung und k\u00f6nnen t\u00e4glich mit der Betreuung von 1 Person beginnen[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343728-6&#8243; tab_id=&#8220;1770137343729-10&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4779&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">HAUPTBERATER<\/span><\/h3>\n<p>Schulungsprogramm Step-Up to Leadership. 1-3 im Team[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343776-0&#8243; tab_id=&#8220;1770137343777-8&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4766&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">TEAMLEITER<\/span><\/h3>\n<p>Fortlaufendes Training f\u00fcr das Programm zur Entwicklung von F\u00fchrungskr\u00e4ften. Team von 3-6[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343816-5&#8243; tab_id=&#8220;1770137343816-1&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4757&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">PRAXISMANAGER<\/span><\/h3>\n<p>Geringere pers\u00f6nliche Abrechnungen und mehr Team-Override mit Schwerpunkt auf der Teamentwicklung und dem durchschnittlichen GP\/FTE. Team von 6-8[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343866-6&#8243; tab_id=&#8220;1770137343867-0&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4748&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">LEITER (H\u00c4NDE WEG)<\/span><\/h3>\n<p>Reine Managementfunktion, Team von 8-10+, je nach Erfahrung des Teams.[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343915-6&#8243; tab_id=&#8220;1770137343916-5&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4739&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">STELLVERTRETENDER DIREKTOR (HANDS-OFF)<\/span><\/h3>\n<p>AD eines Teams von 12-15+ K\u00f6pfen. Die Bezahlung richtet sich ausschlie\u00dflich nach dem Wachstum des Teams in Bezug auf Kopfzahl und GP pro FTE.[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137343976-3&#8243; tab_id=&#8220;1770137343976-0&#8243; title=&#8220;Item&#8220;][image_with_animation image_url=&#8220;4745&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3><span style=\"color: #16c0d8;\">DIREKTOR VON (HANDS-OFF)<\/span><\/h3>\n<p>Sie haben als Direktor die H\u00e4nde frei, um die Gewinn- und Verlustrechnung Ihrer Abteilung zu verbessern, die auf Wachstum und Rentabilit\u00e4t basiert.[\/vc_column_text][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;3991&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;center center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;5%&#8220; top_padding_tablet=&#8220;10%&#8220; constrain_group_3=&#8220;yes&#8220; bottom_padding_tablet=&#8220;10%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;animated-bg&#8220; id=&#8220;Career-paths&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"text-align: center;\">HOW MUCH <span class=\"mobile-block\">CAN YOU<\/span> <span class=\"desktop-block\"><span style=\"color: #13bed7;\">EARN AT SR<\/span>2<\/span><\/h2>\n<p style=\"text-align: center;\">Many agencies claim to have the world\u2019s greatest commission scheme\u2014without ever proving it. We\u2019re not into empty promises. At SR2, we believe in transparency. So, take our Commission Calculator for a spin\u2014plug in your monthly billings and see exactly what you could earn with us.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; left_padding_desktop=&#8220;10%&#8220; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;10%&#8220; left_padding_tablet=&#8220;0&#8243; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;0&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3 style=\"text-align: center;\">PROVISIONSRECHNER UK &amp; EUROPA<\/h3>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]<div class=\"commission-calculator-wrapper single-country\">\n    <div class=\"commission-calculator-left\"><!-- Left --->\n        <div class=\"calculator-form\">\n            \n            <div class=\"input-group hide-single-country\">\n                <label>Country<\/label>\n                    <select name=\"billing-country\" id=\"billing-country\">\n                        <option value=\"UK\" selected>United Kingdom<\/option>\n                    <\/select>\n                <label>Currency<\/label>\n                    <select name=\"bill-currency\" id=\"bill-currency\">\n                        <option value=\"\u00a3\" selected>\u00a3 GBP<\/option>\n                    <\/select>\n            <\/div>\n\n            <hr class=\"hide-single-country\">\n\n            <div class=\"input-group\">\n            <h3 class=\"text-center text-light\">MONTHLY BILLING AMOUNT<\/h3>\n                <input type=\"range\" name=\"bill-amount-range\" value=\"0\" step=\"1000\" min=\"0\" max=\"150000\">\n\n                <div class=\"range-labels text-light\">\n                    <div><span class=\"currency-output\"><\/span>0<\/div>\n                    <div><span class=\"currency-output\"><\/span>150K<\/div>\n                <\/div>\n            <\/div>\n            \n            <div class=\"bill-amount-selected-value text-center text-primary\"><\/div>\n        <\/div>\n\n    <\/div><!--- End left -->\n\n\n    <div class=\"commission-calculator-right\"><!-- Right --->\n        <h3 class=\"text-center text-light\">MONTHLY PAYMENT<\/h3>\n\n        <div class=\"commission-calculculator-right-inner\"><!-- inner -->\n            <div class=\"bill-value bill-amount\">\n                <p class=\"text-center\">MONTHLY AMOUNT<\/p>\n                <div class=\"amount text-center\"><\/div>\n            <\/div>\n            <div class=\"bill-value commission\">\n                <p class=\"text-center\">COMMISSION<\/p>\n                <div class=\"amount text-center\"><\/div>\n            <\/div>\n        <\/div><!-- inner -->\n    <\/div><!---- End right -->\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1741762055911{margin-bottom: 0px !important;}&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; bottom_margin=&#8220;0&#8243; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;10&#8243;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]Die Auszahlung erfolgt im Folgemonat \u2013 also wird der Januar-Umsatz mit dem Februar-Gehalt ausgezahlt. Zus\u00e4tzlich bieten wir ein j\u00e4hrliches Bonusmodell \u2013 gerne mehr dazu im Gespr\u00e4ch![\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;10&#8243; custom_height_tablet=&#8220;5&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][nectar_cta btn_style=&#8220;text-reveal-wave&#8220; heading_tag=&#8220;p&#8220; link_type=&#8220;regular&#8220; button_color=&#8220;accent-color&#8220; text_color=&#8220;#000000&#8243; button_border_thickness=&#8220;0px&#8220; alignment=&#8220;center&#8220; alignment_tablet=&#8220;default&#8220; alignment_phone=&#8220;default&#8220; constrain_group_3=&#8220;yes&#8220; constrain_group_4=&#8220;yes&#8220; display=&#8220;block&#8220; display_tablet=&#8220;inherit&#8220; display_phone=&#8220;inherit&#8220; icon_family=&#8220;none&#8220; link_text=&#8220;WERDEN SIE TEIL UNSERES TEAMS&#8220; url=&#8220;#Contact&#8220; padding_top=&#8220;0.8em&#8220; padding_bottom=&#8220;0.8em&#8220; padding_left=&#8220;2.2em&#8220; padding_right=&#8220;2.2em&#8220; class=&#8220;btn-glow btn-glow-primary commission-calculator-cta&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#13bed7&#8243; color_overlay_2=&#8220;#c5feff&#8220; overlay_strength=&#8220;0.95&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#191919&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;400px&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;straight_section&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; constrain_group_1=&#8220;yes&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"text-align: center;\">HARTE ARBEIT,<br \/>\n<span style=\"color: #ffffff;\">GRO\u00dfE BELOHNUNGEN<\/span><\/h2>\n<p style=\"text-align: center;\">SR2 steht f\u00fcr Leistung, Engagement und Teamspirit. Erfolge werden geb\u00fchrend gefeiert \u2013 mit legend\u00e4ren Teamreisen nach Miami, Las Vegas, Val D\u2019Is\u00e8re, Kroatien, Amsterdam, Palma, Barcelona oder Dubai. \ud83c\udf0d\u2728<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;40px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;5%&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1739267271532{padding-bottom: 5% !important;}&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_video link=&#8220;https:\/\/vimeo.com\/1055187823?share=copy#t=0&#8243; el_width=&#8220;60&#8243; el_aspect=&#8220;916&#8243; align=&#8220;right&#8220; css=&#8220;.vc_custom_1739265273594{border-radius: 10px !important;}&#8220; el_class=&#8220;taste-sr2&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_video link=&#8220;https:\/\/vimeo.com\/1055187870?share=copy#t=0&#8243; el_width=&#8220;60&#8243; el_aspect=&#8220;916&#8243; css=&#8220;.vc_custom_1739265281044{border-radius: 10px !important;}&#8220; el_class=&#8220;taste-sr2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;40px&#8220; equal_height=&#8220;yes&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#191919&#8243; bg_image=&#8220;89&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;center center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;5%&#8220; top_padding_tablet=&#8220;10%&#8220; constrain_group_3=&#8220;yes&#8220; bottom_padding_tablet=&#8220;10%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;animated-bg&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#191919&#8243; color_overlay_2=&#8220;#191919&#8243; overlay_strength=&#8220;1&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;4%&#8220; text_align=&#8220;center&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1739541819198{padding-top: 0px !important;}&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"text-align: center;\">UNSERE WERTE \u2013 <span style=\"color: #13bed7;\">NICHT VERHANDELBAR<\/span><\/h2>\n<p style=\"text-align: center;\">Diese Grunds\u00e4tze sind die Basis unseres Handelns \u2013 ohne Kompromisse:<\/p>\n[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;20px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;center&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#000000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;10px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][nectar_icon icon_family=&#8220;iconsmind&#8220; icon_style=&#8220;shadow-bg&#8220; icon_color_type=&#8220;color_scheme&#8220; icon_color=&#8220;Accent-Color&#8220; icon_padding=&#8220;10px&#8220; pointer_events=&#8220;all&#8220; icon_size=&#8220;40&#8243; icon_iconsmind=&#8220;iconsmind-Diamond&#8220;][divider line_type=&#8220;No Line&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3>HARTE ARBEIT<\/h3>\n<p>Erfolg ist kein Zufall. Bei SR2 z\u00e4hlt harte Arbeit \u2013 Einsatz, Ausdauer und Eigeninitiative sind die Grundlage f\u00fcr echte Ergebnisse. Wir glauben an Hands-on-Mentalit\u00e4t, Engagement und Exzellenz \u2013 Abk\u00fcrzungen gibt es keine.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;center&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#000000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;10px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][nectar_icon icon_family=&#8220;iconsmind&#8220; icon_style=&#8220;shadow-bg&#8220; icon_color_type=&#8220;color_scheme&#8220; icon_color=&#8220;Accent-Color&#8220; icon_padding=&#8220;10px&#8220; pointer_events=&#8220;all&#8220; icon_size=&#8220;40&#8243; icon_iconsmind=&#8220;iconsmind-Add-UserStar&#8220;][divider line_type=&#8220;No Line&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3>VERANTWORTUNG \u00dcBERNEHMEN<\/h3>\n<p>Vertrauen entsteht durch Verl\u00e4sslichkeit. Jedes Teammitglied \u00fcbernimmt Verantwortung f\u00fcr sein Handeln, steht zu seinen Zusagen und handelt transparent. Integrit\u00e4t ist unser Fundament \u2013 sagen, was man tun kann. Tun, was man gesagt hat.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;center&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#000000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;10px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][nectar_icon icon_family=&#8220;iconsmind&#8220; icon_style=&#8220;shadow-bg&#8220; icon_color_type=&#8220;color_scheme&#8220; icon_color=&#8220;Accent-Color&#8220; icon_padding=&#8220;10px&#8220; pointer_events=&#8220;all&#8220; icon_size=&#8220;40&#8243; icon_iconsmind=&#8220;iconsmind-Love-User&#8220;][divider line_type=&#8220;No Line&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3>MENSCHLICH BLEIBEN<\/h3>\n<p>Wertsch\u00e4tzung, Respekt und Empathie pr\u00e4gen unsere Unternehmenskultur \u2013 sowohl im Umgang mit Kund*innen als auch intern. Gutes Miteinander und gesellschaftliche Verantwortung stehen bei uns an erster Stelle.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; bottom_padding=&#8220;3%&#8220; top_padding_tablet=&#8220;10%&#8220; constrain_group_3=&#8220;yes&#8220; bottom_padding_tablet=&#8220;10%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#13bed7&#8243; color_overlay_2=&#8220;#c5feff&#8220; overlay_strength=&#8220;0.95&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"text-align: center;\">LIFE @ <span style=\"color: #ffffff;\">SR2<\/span><\/h2>\n[\/vc_column_text][nectar_btn size=&#8220;medium&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Extra-Color-3&#8243; solid_text_color_override=&#8220;#ffffff&#8220; icon_family=&#8220;fontawesome&#8220; text=&#8220;Auf Instagram entdecken&#8220; url=&#8220;https:\/\/www.instagram.com\/lifeatsr2rec&#8220; icon_fontawesome=&#8220;fa fa-instagram&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\t\t<div id=\"instagram-gallery-feed-0\" class=\"instagram-gallery-feed\" data-feed=\"{&quot;id&quot;:0,&quot;account_id&quot;:&quot;27713143861634646&quot;,&quot;source&quot;:&quot;username&quot;,&quot;tag&quot;:&quot;wordpress&quot;,&quot;order_by&quot;:&quot;top_media&quot;,&quot;layout&quot;:&quot;gallery&quot;,&quot;limit&quot;:12,&quot;columns&quot;:3,&quot;spacing&quot;:10,&quot;lazy&quot;:false,&quot;responsive&quot;:{&quot;desktop&quot;:{&quot;columns&quot;:3,&quot;spacing&quot;:10},&quot;tablet&quot;:{&quot;columns&quot;:2,&quot;spacing&quot;:8},&quot;mobile&quot;:{&quot;columns&quot;:1,&quot;spacing&quot;:6},&quot;breakpoints&quot;:{&quot;tablet&quot;:768,&quot;mobile&quot;:480}},&quot;aspect_ratio&quot;:{&quot;width&quot;:1,&quot;height&quot;:1},&quot;highlight&quot;:{&quot;tag&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;position&quot;:&quot;1,3,5&quot;},&quot;reel&quot;:{&quot;hide&quot;:false},&quot;copyright&quot;:{&quot;hide&quot;:false,&quot;placeholder&quot;:&quot;&quot;},&quot;profile&quot;:{&quot;display&quot;:false,&quot;username&quot;:&quot;&quot;,&quot;nickname&quot;:&quot;&quot;,&quot;website&quot;:&quot;&quot;,&quot;biography&quot;:&quot;&quot;,&quot;link_text&quot;:&quot;Follow&quot;,&quot;website_text&quot;:&quot;Website&quot;,&quot;avatar&quot;:&quot;&quot;},&quot;box&quot;:{&quot;display&quot;:false,&quot;padding&quot;:1,&quot;radius&quot;:0,&quot;background&quot;:&quot;#fefefe&quot;,&quot;profile&quot;:false,&quot;desc&quot;:&quot;&quot;,&quot;text_color&quot;:&quot;#000000&quot;},&quot;mask&quot;:{&quot;display&quot;:true,&quot;background&quot;:&quot;#000000&quot;,&quot;icon_color&quot;:&quot;#ffffff&quot;,&quot;likes_count&quot;:true,&quot;comments_count&quot;:true},&quot;card&quot;:{&quot;display&quot;:false,&quot;radius&quot;:1,&quot;font_size&quot;:12,&quot;background&quot;:&quot;#ffffff&quot;,&quot;background_hover&quot;:&quot;&quot;,&quot;text_color&quot;:&quot;#000000&quot;,&quot;padding&quot;:5,&quot;likes_count&quot;:true,&quot;text_length&quot;:10,&quot;comments_count&quot;:true,&quot;text_align&quot;:&quot;left&quot;},&quot;carousel&quot;:{&quot;centered_slides&quot;:false,&quot;autoplay&quot;:false,&quot;autoplay_interval&quot;:3000,&quot;navarrows&quot;:true,&quot;navarrows_color&quot;:&quot;&quot;,&quot;pagination&quot;:true,&quot;pagination_color&quot;:&quot;&quot;},&quot;modal&quot;:{&quot;display&quot;:true,&quot;profile&quot;:true,&quot;media_description&quot;:true,&quot;likes_count&quot;:true,&quot;comments_count&quot;:true,&quot;comments_list&quot;:false,&quot;text_align&quot;:&quot;left&quot;,&quot;modal_align&quot;:&quot;right&quot;,&quot;text_length&quot;:10000,&quot;font_size&quot;:12},&quot;button&quot;:{&quot;display&quot;:true,&quot;text&quot;:&quot;View on Instagram&quot;,&quot;text_color&quot;:&quot;#ffff&quot;,&quot;background&quot;:&quot;&quot;,&quot;background_hover&quot;:&quot;&quot;},&quot;button_load&quot;:{&quot;display&quot;:false,&quot;text&quot;:&quot;Load more...&quot;,&quot;text_color&quot;:&quot;#ffff&quot;,&quot;background&quot;:&quot;&quot;,&quot;background_hover&quot;:&quot;&quot;}}\">\n\t\t<!-- <FeedContainer\/> -->\n\t\t<\/div>\n\t\t[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;40px&#8220; equal_height=&#8220;yes&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#191919&#8243; bg_image=&#8220;89&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;center center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;5%&#8220; top_padding_tablet=&#8220;10%&#8220; constrain_group_3=&#8220;yes&#8220; bottom_padding_tablet=&#8220;10%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;animated-bg&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#191919&#8243; color_overlay_2=&#8220;#191919&#8243; overlay_strength=&#8220;1&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#ffffff&#8220; shape_divider_position=&#8220;top&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;straight_section&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;center&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>UNSERE BENEFITS \u2013 IHR LEBEN, <span style=\"color: #13bed7;\">IHRE WAHL<\/span><\/h2>\n<p>Wir wissen: Jeder Mensch ist anders. Deshalb ist unser Benefit-Paket flexibel \u2013 mit einem monatlichen Budget k\u00f6nnen individuell passende Leistungen gew\u00e4hlt werden. Ob private Krankenversicherung mit Vitality, Fitnessstudio-Mitgliedschaft oder andere Extras \u2013 Sie entscheiden.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;60px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;6%&#8220; top_padding_tablet=&#8220;10%&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; class=&#8220;custom-accordion-tabs benefits&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; el_class=&#8220;locations&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>28 URLAUBSTAGE + 1 ZUS\u00c4TZLICHER TAG PRO VOLLEM JAHR BETRIEBSZUGEH\u00d6RIGKEIT<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>GEBURTSTAG FREI<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>TEAM-BOOTCAMPS JEDEN MONTAG<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>MENTALE GESUNDHEITSANGEBOTE MIT TALK CLUB<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>FREITAG IST UM 16 UHR FEIERABEND<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>MONATLICHE LUNCH CLUBS<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>2 URLAUBS-INCENTIVES PRO JAHR<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>QUARTALSWEISE TEAM-EVENTS<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h3>HYBRIDES ARBEITEN<\/h3>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;center&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;2917&#8243; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;front&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#000000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;10px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; el_class=&#8220;custom-toggle-tabs-descriptions&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;300&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;5%&#8220; top_padding_tablet=&#8220;10%&#8220; constrain_group_3=&#8220;yes&#8220; bottom_padding_tablet=&#8220;10%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;SR2-Jobs&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#13bed7&#8243; color_overlay_2=&#8220;#c5feff&#8220; overlay_strength=&#8220;0.95&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"text-align: center;\">WERDEN SIE TEIL UNSERER <span style=\"color: #ffffff;\">REISE<\/span><\/h2>\n<p style=\"text-align: center;\">Wer ehrgeizig, motiviert und auf der Suche nach echter Wirkung ist \u2013 in der Branche und dar\u00fcber hinaus \u2013 ist bei uns genau richtig. Wir suchen die Besten ihres Fachs. Interesse? Jetzt bewerben und mit uns Kontakt aufnehmen!<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;job-listings-preview&#8220;]    <div class=\"jobs-grid\">\n        <div class=\"jobs-grid-wrapper\">\n            <ul class='jobs-list-preview-wrapper job-listing-cards job-listings-preview'><\/ul>\n        <\/div>\n        <!-- <div class=\"jobs-count\"><\/div> -->\n        <div class=\"load-more-jobs-wrapper\">\n            <button id=\"load-more-jobs\" class=\"button button-primary button-center\">Load more<\/button>\n            <!-- <p class=\"loading-illustration\">Loading ...<\/p> -->\n        <\/div>\n    <\/div>\n    [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#191919&#8243; bg_image=&#8220;89&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;center center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;5%&#8220; top_padding_tablet=&#8220;10%&#8220; constrain_group_3=&#8220;yes&#8220; bottom_padding_tablet=&#8220;10%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;animated-bg&#8220; id=&#8220;Testimonials&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#191919&#8243; color_overlay_2=&#8220;#191919&#8243; overlay_strength=&#8220;1&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"text-align: center;\">WAS UNSER <span style=\"color: #14bed7;\">TEAM<\/span> SAGT<\/h2>\n[\/vc_column_text][carousel script=&#8220;flickity&#8220; flickity_formatting=&#8220;default&#8220; desktop_cols_flickity=&#8220;3&#8243; desktop_small_cols_flickity=&#8220;3&#8243; tablet_cols_flickity=&#8220;2&#8243; phone_cols_flickity=&#8220;1&#8243; flickity_controls=&#8220;next_prev_arrows_overlaid&#8220; color=&#8220;default&#8220; flickity_overflow=&#8220;visible&#8220; flickity_wrap_around=&#8220;wrap&#8220; flickity_spacing=&#8220;default&#8220; flickity_column_vertical_alignment=&#8220;default&#8220; column_padding=&#8220;0&#8243; flickity_element_spacing=&#8220;default&#8220; border_radius=&#8220;none&#8220;][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137345537-8&#8243; tab_id=&#8220;1770137345538-5&#8243; title=&#8220;Item&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][nectar_flip_box image_url_1=&#8220;2413&#8243; text_color=&#8220;light&#8220; icon_color=&#8220;accent-color&#8220; bg_color_2=&#8220;#13bed7&#8243; text_color_2=&#8220;dark&#8220; h_text_align=&#8220;left&#8220; v_text_align=&#8220;top&#8220; image_loading=&#8220;default&#8220; flip_direction=&#8220;horizontal-to-left&#8220; min_height=&#8220;350&#8243;]\n<h3>Ellen Kain<\/h3>\n<h4>Leiter der Abteilung Contractor Care<\/h4>\n<p>&#8222;Das gesamte Team wei\u00df zu sch\u00e4tzen, wie hart das Ops-Team arbeitet und versteht, warum wir tun m\u00fcssen, was wir tun. Sie arbeiten mit uns und nicht gegen uns, etwas, das ich noch nie erlebt habe. Ich k\u00f6nnte immer so weitermachen! Ich bin sehr gl\u00fccklich bei SR2. Chris hat einen unglaublichen Job gemacht und daf\u00fcr gesorgt, dass sich jeder geh\u00f6rt f\u00fchlt. Die Werte des Unternehmens sind unser Brot und Butter und nicht nur eine gute Marketingkampagne f\u00fcr die sozialen Medien. Was Sie sehen, ist das, was Sie bekommen, und so viel mehr!&#8220;[\/nectar_flip_box][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137345737-5&#8243; tab_id=&#8220;1770137345738-4&#8243; title=&#8220;Item&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][nectar_flip_box image_url_1=&#8220;2426&#8243; text_color=&#8220;light&#8220; icon_color=&#8220;accent-color&#8220; bg_color_2=&#8220;#13bed7&#8243; text_color_2=&#8220;dark&#8220; h_text_align=&#8220;left&#8220; v_text_align=&#8220;top&#8220; image_loading=&#8220;default&#8220; flip_direction=&#8220;horizontal-to-left&#8220; min_height=&#8220;250&#8243;]\n<h3>Kelly Morgans<\/h3>\n<h4>Leitender Hauptberater<\/h4>\n<p>&#8222;Ich war neugierig auf die Marke und die Art und Weise, wie SR2 engen Kontakt zu seinen Kunden und Kandidaten h\u00e4lt. Das Team ist voller positiver Schwingungen und ich hatte das Gef\u00fchl, dass man wie ein Erwachsener behandelt wird und dass man flexibel ist, sobald ich zum Vorstellungsgespr\u00e4ch hereinkam. Ich f\u00fchle mich in einem Umfeld, in dem mir vertraut wird, meine Meinung gesch\u00e4tzt wird, jeder respektiert und gleich behandelt wird und wir alle eine Mission haben und gemeinsam auf dieser Reise sind.&#8220;[\/nectar_flip_box][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137345807-4&#8243; tab_id=&#8220;1770137345807-3&#8243; title=&#8220;Item&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][nectar_flip_box image_url_1=&#8220;2423&#8243; text_color=&#8220;light&#8220; icon_color=&#8220;accent-color&#8220; bg_color_2=&#8220;#13bed7&#8243; text_color_2=&#8220;dark&#8220; h_text_align=&#8220;left&#8220; v_text_align=&#8220;top&#8220; image_loading=&#8220;default&#8220; flip_direction=&#8220;horizontal-to-left&#8220; min_height=&#8220;350&#8243;]\n<h3>Joe Wannell<\/h3>\n<h4>Senior Berater<\/h4>\n<p>&#8222;Das Wichtigste zuerst: Die Leute sind fantastisch. Keine Kollegen, sondern echte Freunde. Ich m\u00f6chte nie von zu Hause aus arbeiten, weil das B\u00fcro so lebendig ist. Es gibt so viele M\u00f6glichkeiten, gut zu arbeiten und seine Karriere voranzutreiben.&#8220;[\/nectar_flip_box][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137345881-1&#8243; tab_id=&#8220;1770137345882-9&#8243; title=&#8220;Item&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][nectar_flip_box image_url_1=&#8220;2432&#8243; text_color=&#8220;light&#8220; icon_color=&#8220;accent-color&#8220; bg_color_2=&#8220;#13bed7&#8243; text_color_2=&#8220;dark&#8220; h_text_align=&#8220;left&#8220; v_text_align=&#8220;top&#8220; image_loading=&#8220;default&#8220; flip_direction=&#8220;horizontal-to-left&#8220; min_height=&#8220;250&#8243;]\n<h3>Steve Dalley<\/h3>\n<h4>Leitender Berater<\/h4>\n<p>&#8222;Ich war bereit, die Personalvermittlung an den Nagel zu h\u00e4ngen, weil ich dachte, die gesamte Branche sei sehr unternehmensorientiert und auf KPIs ausgerichtet. Ich habe mit Chris und Marius gesprochen und fast dreieinhalb Jahre sp\u00e4ter bin ich immer noch hier! Das, was SR2 f\u00fcr die Gemeinschaft tut, ist einzigartig und die Kultur wird durch die Tatsache verk\u00f6rpert, dass ich 8 Stunden am Tag mit allen verbringe und dann auch noch das Wochenende mit ihnen verbringe. Die M\u00f6glichkeiten, die SR2 sowohl f\u00fcr die pers\u00f6nliche als auch f\u00fcr die berufliche Entwicklung bietet, sind erstaunlich![\/nectar_flip_box][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137346009-9&#8243; tab_id=&#8220;1770137346010-8&#8243; title=&#8220;Item&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][nectar_flip_box image_url_1=&#8220;2435&#8243; text_color=&#8220;light&#8220; icon_color=&#8220;accent-color&#8220; bg_color_2=&#8220;#13bed7&#8243; text_color_2=&#8220;dark&#8220; h_text_align=&#8220;left&#8220; v_text_align=&#8220;top&#8220; image_loading=&#8220;default&#8220; flip_direction=&#8220;horizontal-to-left&#8220; min_height=&#8220;250&#8243;]\n<h3>Tom Longden<\/h3>\n<h4>Teamleiter<\/h4>\n<p>&#8222;Die Unterst\u00fctzung bei SR2 ist hervorragend. Mein erstes Jahr in der Rekrutierung ging in die Hose. Marius und Chris haben den Glauben an mich behalten (auch wenn ich ihn fast verloren hatte). Nach 2 bis 3 Jahren habe ich dann 4 Bef\u00f6rderungen erreicht, bin in eine neue Stadt gezogen und habe mein Leben ver\u00e4ndert! Die Qualit\u00e4t der Personalberater hier ist erstklassig, aber sie sind als Menschen noch besser. Jeder will, dass jeder Erfolg hat, und ich habe dank SR2 einige meiner engsten Freunde.&#8220;[\/nectar_flip_box][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8220;default&#8220; simple_slider_overlay_strength=&#8220;0.3&#8243; simple_slider_bg_image_loading=&#8220;default&#8220; flickity_bg_image_loading=&#8220;default&#8220; flex_gap_desktop=&#8220;10px&#8220; flickity_item_link_type=&#8220;regular&#8220; id=&#8220;1770137346098-0&#8243; tab_id=&#8220;1770137346099-7&#8243; title=&#8220;Item&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][nectar_flip_box image_url_1=&#8220;2438&#8243; text_color=&#8220;light&#8220; icon_color=&#8220;accent-color&#8220; bg_color_2=&#8220;#13bed7&#8243; text_color_2=&#8220;dark&#8220; h_text_align=&#8220;left&#8220; v_text_align=&#8220;top&#8220; image_loading=&#8220;default&#8220; flip_direction=&#8220;horizontal-to-left&#8220; min_height=&#8220;250&#8243;]\n<h3>Doug Gear<\/h3>\n<h4>Senior Berater<\/h4>\n<p>&#8222;Ich habe mich f\u00fcr SR2 entschieden, weil sie die Personalbeschaffung anders angehen &#8211; sie leisten einen sinnvollen Beitrag zur Gesellschaft und stellen den Menschen in den Mittelpunkt. Jeder im Unternehmen ist auf der gleichen Wellenl\u00e4nge, es ist also gro\u00dfartig, mit einer Menge gleichgesinnter Legenden zusammenzuarbeiten.[\/nectar_flip_box][\/vc_column_inner][\/vc_row_inner][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;Contact&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_global_section id=&#8220;5310&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; full_height=&#8220;yes&#8220; video_bg=&#8220;use_video&#8220; video_mp4=&#8220;https:\/\/sr2rec.com\/wp-content\/uploads\/2025\/03\/Website-homepage_V5_27_08_2024-1.mp4&#8243; background_video_loading=&#8220;default&#8220; scene_position=&#8220;center&#8220; constrain_group_1=&#8220;yes&#8220; constrain_group_3=&#8220;yes&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#000000&#8243; color_overlay_2=&#8220;#000000&#8243; advanced_gradient_angle=&#8220;180&#8243; overlay_strength=&#8220;0.5&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-5257","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karriere bei SR2 - SR2 Recruitment Group<\/title>\n<meta name=\"description\" content=\"Wenn Sie hier sind, suchen Sie nicht nur einen Job - Sie sind zielstrebig, ehrgeizig und bereit, eine Karriere aufzubauen, die Sie zu H\u00f6chstleistungen anspornt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sr2rec.com\/de\/karriere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karriere bei SR2 - SR2 Recruitment Group\" \/>\n<meta property=\"og:description\" content=\"Wenn Sie hier sind, suchen Sie nicht nur einen Job - Sie sind zielstrebig, ehrgeizig und bereit, eine Karriere aufzubauen, die Sie zu H\u00f6chstleistungen anspornt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sr2rec.com\/de\/karriere\/\" \/>\n<meta property=\"og:site_name\" content=\"SR2 Recruitment Group\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T16:49:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sr2rec.com\/wp-content\/uploads\/2025\/04\/SR2-FB-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/karriere\\\/\",\"url\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/karriere\\\/\",\"name\":\"Karriere bei SR2 - SR2 Recruitment Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/#website\"},\"datePublished\":\"2024-11-29T20:54:07+00:00\",\"dateModified\":\"2026-02-03T16:49:23+00:00\",\"description\":\"Wenn Sie hier sind, suchen Sie nicht nur einen Job - Sie sind zielstrebig, ehrgeizig und bereit, eine Karriere aufzubauen, die Sie zu H\u00f6chstleistungen anspornt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/karriere\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sr2rec.com\\\/de\\\/karriere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/karriere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karriere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/\",\"name\":\"SR2 Recruitment Group\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sr2rec.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karriere bei SR2 - SR2 Recruitment Group","description":"Wenn Sie hier sind, suchen Sie nicht nur einen Job - Sie sind zielstrebig, ehrgeizig und bereit, eine Karriere aufzubauen, die Sie zu H\u00f6chstleistungen anspornt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sr2rec.com\/de\/karriere\/","og_locale":"de_DE","og_type":"article","og_title":"Karriere bei SR2 - SR2 Recruitment Group","og_description":"Wenn Sie hier sind, suchen Sie nicht nur einen Job - Sie sind zielstrebig, ehrgeizig und bereit, eine Karriere aufzubauen, die Sie zu H\u00f6chstleistungen anspornt.","og_url":"https:\/\/sr2rec.com\/de\/karriere\/","og_site_name":"SR2 Recruitment Group","article_modified_time":"2026-02-03T16:49:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/sr2rec.com\/wp-content\/uploads\/2025\/04\/SR2-FB-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sr2rec.com\/de\/karriere\/","url":"https:\/\/sr2rec.com\/de\/karriere\/","name":"Karriere bei SR2 - SR2 Recruitment Group","isPartOf":{"@id":"https:\/\/sr2rec.com\/de\/#website"},"datePublished":"2024-11-29T20:54:07+00:00","dateModified":"2026-02-03T16:49:23+00:00","description":"Wenn Sie hier sind, suchen Sie nicht nur einen Job - Sie sind zielstrebig, ehrgeizig und bereit, eine Karriere aufzubauen, die Sie zu H\u00f6chstleistungen anspornt.","breadcrumb":{"@id":"https:\/\/sr2rec.com\/de\/karriere\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sr2rec.com\/de\/karriere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sr2rec.com\/de\/karriere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sr2rec.com\/de\/"},{"@type":"ListItem","position":2,"name":"Karriere"}]},{"@type":"WebSite","@id":"https:\/\/sr2rec.com\/de\/#website","url":"https:\/\/sr2rec.com\/de\/","name":"SR2 Recruitment Group","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sr2rec.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/pages\/5257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/comments?post=5257"}],"version-history":[{"count":19,"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/pages\/5257\/revisions"}],"predecessor-version":[{"id":11237,"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/pages\/5257\/revisions\/11237"}],"wp:attachment":[{"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/media?parent=5257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/categories?post=5257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sr2rec.com\/de\/wp-json\/wp\/v2\/tags?post=5257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}